{"id":9,"date":"2026-03-24T10:56:30","date_gmt":"2026-03-24T09:56:30","guid":{"rendered":""},"modified":"2026-05-05T16:06:50","modified_gmt":"2026-05-05T14:06:50","slug":"mentions-legales","status":"publish","type":"page","link":"https:\/\/cytec-europe.com\/en\/mentions-legales\/","title":{"rendered":"Legal notice"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"9\" class=\"elementor elementor-9\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9b3839 e-con-full e-flex e-con e-parent\" data-id=\"f9b3839\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53fa91b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"53fa91b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Legal notice<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f022f0f e-con-full e-flex e-con e-parent\" data-id=\"f022f0f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e3f7619 e-con-full e-flex e-con e-child\" data-id=\"e3f7619\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d77f4ea elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d77f4ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>1. Pr\u00e9sentation du site.<\/h3><p>En vertu de l\u2019article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l\u2019\u00e9conomie num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site l\u2019identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi :<\/p><ul><li>Propri\u00e9taire : CYTEC, Rue de Lorraine, 57380 FAULQUEMONT<\/li><li>Cr\u00e9ateur du site : D\u00e9clic Communication<\/li><li>Responsable publication : Jean-Michel PROVOT &#8211; 03 87 00 30 40<\/li><li>Le responsable publication est une personne physique ou une personne morale.<\/li><li>Webmaster : Jean-Michel PROVOT &#8211; 03 87 00 30 40<\/li><li>H\u00e9bergeur : OVH SAS &#8211; 2 rue Kellermann \u2013 BP 80157 \u2013 59053 Roubaix Cedex 1<\/li><li>Cr\u00e9dits Photos : Adobe Stock \u2013 D\u00e9clic Communication<br \/><br \/><\/li><\/ul><p>Informations juridiques :<\/p><ul><li>SAS au capital de 100 000,00 \u20ac<\/li><li>SIREN : 420 433 229<\/li><li>SIRET : 420 433 229 00036<\/li><li>APE : 2222Z &#8211; Fabrication d&#8217;emballages en mati\u00e8res plastiques<\/li><\/ul><h3>\u00a0<\/h3><h3>2. Conditions g\u00e9n\u00e9rales d\u2019utilisation du site et des services propos\u00e9s.<\/h3><p>L\u2019utilisation du site implique l\u2019acceptation pleine et enti\u00e8re des conditions g\u00e9n\u00e9rales d\u2019utilisation ci-apr\u00e8s d\u00e9crites. Ces conditions d\u2019utilisation sont susceptibles d\u2019\u00eatre modifi\u00e9es ou compl\u00e9t\u00e9es \u00e0 tout moment, les utilisateurs du site sont donc invit\u00e9s \u00e0 les consulter de mani\u00e8re r\u00e9guli\u00e8re. Ce site est normalement accessible \u00e0 tout moment aux utilisateurs. Une interruption pour raison de maintenance technique peut \u00eatre toutefois d\u00e9cid\u00e9e par CYTEC, qui s\u2019efforcera alors de communiquer pr\u00e9alablement aux utilisateurs les dates et heures de l\u2019intervention. Le site est mis \u00e0 jour r\u00e9guli\u00e8rement par Jean-Michel PROVOT. De la m\u00eame fa\u00e7on, les mentions l\u00e9gales peuvent \u00eatre modifi\u00e9es \u00e0 tout moment : elles s\u2019imposent n\u00e9anmoins \u00e0 l\u2019utilisateur qui est invit\u00e9 \u00e0 s\u2019y r\u00e9f\u00e9rer le plus souvent possible afin d\u2019en prendre connaissance.<\/p><h1>\u00a0<\/h1><h3>3. Description des services fournis.<\/h3><p>Le site a pour objet de fournir une information concernant l\u2019ensemble des activit\u00e9s de la soci\u00e9t\u00e9. D\u00e9clic Communication s\u2019efforce de fournir sur le site des informations aussi pr\u00e9cises que possible. Toutefois, il ne pourra \u00eatre tenue responsable des omissions, des inexactitudes et des carences dans la mise \u00e0 jour, qu\u2019elles soient de son fait ou du fait des tiers partenaires qui lui fournissent ces informations. Tous les informations indiqu\u00e9es sur le site sont donn\u00e9es \u00e0 titre indicatif, et sont susceptibles d\u2019\u00e9voluer. Par ailleurs, les renseignements figurant sur le site ne sont pas exhaustifs. Ils sont donn\u00e9s sous r\u00e9serve de modifications ayant \u00e9t\u00e9 apport\u00e9es depuis leur mise en ligne.<\/p><h1>\u00a0<\/h1><h3>4. Limitations contractuelles sur les donn\u00e9es techniques.<\/h3><p>Le site utilise la technologie JavaScript. Le site Internet ne pourra \u00eatre tenu responsable de dommages mat\u00e9riels li\u00e9s \u00e0 l\u2019utilisation du site. De plus, l\u2019utilisateur du site s\u2019engage \u00e0 acc\u00e9der au site en utilisant un mat\u00e9riel r\u00e9cent, ne contenant pas de virus et avec un navigateur de derni\u00e8re g\u00e9n\u00e9ration mis-\u00e0-jour<\/p><h1>\u00a0<\/h1><h3>5. Propri\u00e9t\u00e9 intellectuelle et contrefa\u00e7ons.<\/h3><p>CYTEC est propri\u00e9taire des droits de propri\u00e9t\u00e9 intellectuelle ou d\u00e9tient les droits d\u2019usage sur tous les \u00e9l\u00e9ments accessibles sur le site, notamment les textes, images, graphismes, logo, ic\u00f4nes, sons, logiciels. Toute reproduction, repr\u00e9sentation, modification, publication, adaptation de tout ou partie des \u00e9l\u00e9ments du site, quel que soit le moyen ou le proc\u00e9d\u00e9 utilis\u00e9, est interdite, sauf autorisation \u00e9crite pr\u00e9alable de : CYTEC. Toute exploitation non autoris\u00e9e du site ou de l\u2019un quelconque des \u00e9l\u00e9ments qu\u2019il contient sera consid\u00e9r\u00e9e comme constitutive d\u2019une contrefa\u00e7on et poursuivie conform\u00e9ment aux dispositions des articles L.335-2 et suivants du Code de Propri\u00e9t\u00e9 Intellectuelle.<\/p><h1>\u00a0<\/h1><h3>6. Limitations de responsabilit\u00e9.<\/h3><p>CYTEC ne pourra \u00eatre tenue responsable des dommages directs et indirects caus\u00e9s au mat\u00e9riel de l\u2019utilisateur, lors de l\u2019acc\u00e8s au site , et r\u00e9sultant soit de l\u2019utilisation d\u2019un mat\u00e9riel ne r\u00e9pondant pas aux sp\u00e9cifications indiqu\u00e9es au point 4, soit de l\u2019apparition d\u2019un bug ou d\u2019une incompatibilit\u00e9. CYTEC ne pourra \u00e9galement \u00eatre tenue responsable des dommages indirects (tels par exemple qu\u2019une perte de march\u00e9 ou perte d\u2019une chance) cons\u00e9cutifs \u00e0 l\u2019utilisation du site . Des espaces interactifs (possibilit\u00e9 de poser des questions dans l\u2019espace contact) sont \u00e0 la disposition des utilisateurs. CYTEC se r\u00e9serve le droit de supprimer, sans mise en demeure pr\u00e9alable, tout contenu d\u00e9pos\u00e9 dans cet espace qui contreviendrait \u00e0 la l\u00e9gislation applicable en France, en particulier aux dispositions relatives \u00e0 la protection des donn\u00e9es. Le cas \u00e9ch\u00e9ant, CYTEC se r\u00e9serve \u00e9galement la possibilit\u00e9 de mettre en cause la responsabilit\u00e9 civile et\/ou p\u00e9nale de l\u2019utilisateur, notamment en cas de message \u00e0 caract\u00e8re raciste, injurieux, diffamant, ou pornographique, quel que soit le support utilis\u00e9 (texte, photographie\u2026).<\/p><h1>\u00a0<\/h1><h3>7. Gestion des donn\u00e9es personnelles.<\/h3><p>En France, les donn\u00e9es personnelles sont notamment prot\u00e9g\u00e9es par la loi n\u00b0 78-87 du 6 janvier 1978, la loi n\u00b0 2004-801 du 6 ao\u00fbt 2004, l\u2019article L. 226-13 du Code p\u00e9nal et la Directive Europ\u00e9enne du 24 octobre 1995. A l\u2019occasion de l\u2019utilisation du site , peuvent \u00eatres recueillies : l\u2019URL des liens par l\u2019interm\u00e9diaire desquels l\u2019utilisateur a acc\u00e9d\u00e9 au site , le fournisseur d\u2019acc\u00e8s de l\u2019utilisateur, l\u2019adresse de protocole Internet (IP) de l\u2019utilisateur. En tout \u00e9tat de cause CYTEC ne collecte des informations personnelles relatives \u00e0 l\u2019utilisateur que pour le besoin de certains services propos\u00e9s par le site . L\u2019utilisateur fournit ces informations en toute connaissance de cause, notamment lorsqu\u2019il proc\u00e8de par lui-m\u00eame \u00e0 leur saisie. Il est alors pr\u00e9cis\u00e9 \u00e0 l\u2019utilisateur du site l\u2019obligation ou non de fournir ces informations. Conform\u00e9ment aux dispositions des articles 38 et suivants de la loi 78-17 du 6 janvier 1978 relative \u00e0 l\u2019informatique, aux fichiers et aux libert\u00e9s, tout utilisateur dispose d\u2019un droit d\u2019acc\u00e8s, de rectification et d\u2019opposition aux donn\u00e9es personnelles le concernant, en effectuant sa demande \u00e9crite et sign\u00e9e, accompagn\u00e9e d\u2019une copie du titre d\u2019identit\u00e9 avec signature du titulaire de la pi\u00e8ce, en pr\u00e9cisant l\u2019adresse \u00e0 laquelle la r\u00e9ponse doit \u00eatre envoy\u00e9e. Aucune information personnelle de l\u2019utilisateur du site n\u2019est publi\u00e9e \u00e0 l\u2019insu de l\u2019utilisateur, \u00e9chang\u00e9e, transf\u00e9r\u00e9e, c\u00e9d\u00e9e ou vendue sur un support quelconque \u00e0 des tiers. Seule l\u2019hypoth\u00e8se du rachat de CYTEC et de ses droits permettrait la transmission des dites informations \u00e0 l\u2019\u00e9ventuel acqu\u00e9reur qui serait \u00e0 son tour tenu de la m\u00eame obligation de conservation et de modification des donn\u00e9es vis \u00e0 vis de l\u2019utilisateur du site . Les bases de donn\u00e9es sont prot\u00e9g\u00e9es par les dispositions de la loi du 1er juillet 1998 transposant la directive 96\/9 du 11 mars 1996 relative \u00e0 la protection juridique des bases de donn\u00e9es.<\/p><h1>\u00a0<\/h1><h3>8. Liens hypertextes et cookies.<\/h3><p>Le site contient un certain nombre de liens hypertextes vers d\u2019autres sites, mis en place avec l\u2019autorisation de CYTEC. Cependant, CYTEC n\u2019a pas la possibilit\u00e9 de v\u00e9rifier le contenu des sites ainsi visit\u00e9s, et n\u2019assumera en cons\u00e9quence aucune responsabilit\u00e9 de ce fait. La navigation sur le site est susceptible de provoquer l\u2019installation de cookie(s) sur l\u2019ordinateur de l\u2019utilisateur. Un cookie est un fichier de petite taille, qui ne permet pas l\u2019identification de l\u2019utilisateur, mais qui enregistre des informations relatives \u00e0 la navigation d\u2019un ordinateur sur un site. Les donn\u00e9es ainsi obtenues visent \u00e0 faciliter la navigation ult\u00e9rieure sur le site, et ont \u00e9galement vocation \u00e0 permettre diverses mesures de fr\u00e9quentation. Le refus d\u2019installation d\u2019un cookie peut entra\u00eener l\u2019impossibilit\u00e9 d\u2019acc\u00e9der \u00e0 certains services. L\u2019utilisateur peut toutefois configurer son ordinateur de la mani\u00e8re suivante, pour refuser l\u2019installation des cookies :<\/p><ul><li>Sous Internet Explorer : onglet outil (pictogramme en forme de rouage en haut \u00e0 droite) \/ options internet. Cliquez sur Confidentialit\u00e9 et choisissez Bloquer tous les cookies. Validez sur Ok.<\/li><li>Sous Firefox : en haut de la fen\u00eatre du navigateur, cliquez sur le bouton Firefox, puis aller dans l\u2019onglet Options. Cliquer sur l\u2019onglet Vie priv\u00e9e. Param\u00e9trez les R\u00e8gles de conservation sur : utiliser les param\u00e8tres personnalis\u00e9s pour l\u2019historique. Enfin d\u00e9cochez-la pour d\u00e9sactiver les cookies.<\/li><li>Sous Safari : Cliquez en haut \u00e0 droite du navigateur sur le pictogramme de menu (symbolis\u00e9 par un rouage). S\u00e9lectionnez Param\u00e8tres. Cliquez sur Afficher les param\u00e8tres avanc\u00e9s. Dans la section \u00ab Confidentialit\u00e9 \u00bb, cliquez sur Param\u00e8tres de contenu. Dans la section \u00ab Cookies \u00bb, vous pouvez bloquer les cookies.<\/li><li>Sous Chrome : Cliquez en haut \u00e0 droite du navigateur sur le pictogramme de menu (symbolis\u00e9 par trois lignes horizontales). S\u00e9lectionnez Param\u00e8tres. Cliquez sur Afficher les param\u00e8tres avanc\u00e9s. Dans la section \u00ab Confidentialit\u00e9 \u00bb, cliquez sur pr\u00e9f\u00e9rences. Dans l\u2019onglet \u00ab Confidentialit\u00e9 \u00bb, vous pouvez bloquer les cookies.<\/li><\/ul><h1>\u00a0<\/h1><h3>9. Droit applicable et attribution de juridiction.<\/h3><p>Tout litige en relation avec l\u2019utilisation du site est soumis au droit fran\u00e7ais. Il est fait attribution exclusive de juridiction aux tribunaux comp\u00e9tents de Sarreguemines.<\/p><h1>\u00a0<\/h1><h3>10. Les principales lois concern\u00e9es.<\/h3><p>Loi n\u00b0 78-17 du 6 janvier 1978, notamment modifi\u00e9e par la loi n\u00b0 2004-801 du 6 ao\u00fbt 2004 relative \u00e0 l\u2019informatique, aux fichiers et aux libert\u00e9s. Loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l\u2019\u00e9conomie num\u00e9rique.<\/p><h1>\u00a0<\/h1><h3>11. Lexique.<\/h3><ul><li>Utilisateur : Internaute se connectant, utilisant le site susnomm\u00e9.<\/li><li>Informations personnelles : \u00ab les informations qui permettent, sous quelque forme que ce soit, directement ou non, l\u2019identification des personnes physiques auxquelles elles s\u2019appliquent \u00bb (article 4 de la loi n\u00b0 78-17 du 6 janvier 1978).<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Mentions l\u00e9gales 1. Pr\u00e9sentation du site. En vertu de l\u2019article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l\u2019\u00e9conomie num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site l\u2019identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi : Propri\u00e9taire : CYTEC, Rue de Lorraine, 57380 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-9","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mentions l\u00e9gales - CYTEC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cytec-europe.com\/en\/mentions-legales\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mentions l\u00e9gales - CYTEC\" \/>\n<meta property=\"og:description\" content=\"Mentions l\u00e9gales 1. Pr\u00e9sentation du site. En vertu de l\u2019article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l\u2019\u00e9conomie num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site l\u2019identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi : Propri\u00e9taire : CYTEC, Rue de Lorraine, 57380 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cytec-europe.com\/en\/mentions-legales\/\" \/>\n<meta property=\"og:site_name\" content=\"CYTEC\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T14:06:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/mentions-legales\\\/\",\"url\":\"https:\\\/\\\/cytec-europe.com\\\/mentions-legales\\\/\",\"name\":\"Mentions l\u00e9gales - CYTEC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/#website\"},\"datePublished\":\"2026-03-24T09:56:30+00:00\",\"dateModified\":\"2026-05-05T14:06:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/mentions-legales\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cytec-europe.com\\\/mentions-legales\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/mentions-legales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cytec-europe.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mentions l\u00e9gales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/#website\",\"url\":\"https:\\\/\\\/cytec-europe.com\\\/\",\"name\":\"CYTEC\",\"description\":\"CYTEC, entreprise de plasturgie bas\u00e9e en Moselle, sp\u00e9cialis\u00e9e dans la transformation des mati\u00e8res plastiques par thermoformage et rotomoulage.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cytec-europe.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mentions l\u00e9gales - CYTEC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cytec-europe.com\/en\/mentions-legales\/","og_locale":"en_GB","og_type":"article","og_title":"Mentions l\u00e9gales - CYTEC","og_description":"Mentions l\u00e9gales 1. Pr\u00e9sentation du site. En vertu de l\u2019article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l\u2019\u00e9conomie num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site l\u2019identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi : Propri\u00e9taire : CYTEC, Rue de Lorraine, 57380 [&hellip;]","og_url":"https:\/\/cytec-europe.com\/en\/mentions-legales\/","og_site_name":"CYTEC","article_modified_time":"2026-05-05T14:06:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cytec-europe.com\/mentions-legales\/","url":"https:\/\/cytec-europe.com\/mentions-legales\/","name":"Mentions l\u00e9gales - CYTEC","isPartOf":{"@id":"https:\/\/cytec-europe.com\/#website"},"datePublished":"2026-03-24T09:56:30+00:00","dateModified":"2026-05-05T14:06:50+00:00","breadcrumb":{"@id":"https:\/\/cytec-europe.com\/mentions-legales\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cytec-europe.com\/mentions-legales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cytec-europe.com\/mentions-legales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cytec-europe.com\/"},{"@type":"ListItem","position":2,"name":"Mentions l\u00e9gales"}]},{"@type":"WebSite","@id":"https:\/\/cytec-europe.com\/#website","url":"https:\/\/cytec-europe.com\/","name":"CYTEC","description":"CYTEC, entreprise de plasturgie bas\u00e9e en Moselle, sp\u00e9cialis\u00e9e dans la transformation des mati\u00e8res plastiques par thermoformage et rotomoulage.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cytec-europe.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/types\/page"}],"replies":[{"embeddable":true,"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":3,"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"predecessor-version":[{"id":2794,"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/pages\/9\/revisions\/2794"}],"wp:attachment":[{"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}