{"id":8,"date":"2026-03-24T09:51:33","date_gmt":"2026-03-24T08:51:33","guid":{"rendered":""},"modified":"2026-05-05T13:31:14","modified_gmt":"2026-05-05T11:31:14","slug":"actualites","status":"publish","type":"page","link":"https:\/\/cytec-europe.com\/en\/actualites\/","title":{"rendered":"News"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8\" class=\"elementor elementor-8\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ab9e91 e-con-full e-flex e-con e-parent\" data-id=\"9ab9e91\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71e5a92 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"71e5a92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Actualit\u00e9s<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b88b4de e-con-full e-flex e-con e-parent\" data-id=\"b88b4de\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2645b67 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"2645b67\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:240,&quot;columns&quot;:3,&quot;pagination_type&quot;:&quot;numbers_and_prev_next&quot;,&quot;_skin&quot;:&quot;post&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;pagination_load_type&quot;:&quot;page_reload&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-240\">.elementor-240 .elementor-element.elementor-element-48639b8{--display:flex;--gap:0px 0px;--row-gap:0px;--column-gap:0px;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-widget-image .widget-image-caption{color:var( --e-global-color-text );font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-weight:var( --e-global-typography-text-font-weight );}.elementor-240 .elementor-element.elementor-element-3582654 img{width:100%;height:400px;object-fit:cover;object-position:center center;}.elementor-240 .elementor-element.elementor-element-804f584{--display:flex;--padding-top:3%;--padding-bottom:3%;--padding-left:6%;--padding-right:6%;}.elementor-240 .elementor-element.elementor-element-804f584:not(.elementor-motion-effects-element-type-background), .elementor-240 .elementor-element.elementor-element-804f584 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:var( --e-global-color-secondary );}.elementor-widget-text-editor{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-weight:var( --e-global-typography-text-font-weight );color:var( --e-global-color-text );}.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:var( --e-global-color-primary );}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap, .elementor-widget-text-editor.elementor-drop-cap-view-default .elementor-drop-cap{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-240 .elementor-element.elementor-element-8e57bd4{font-family:\"bc-novatica-cyr\", Sans-serif;font-size:20px;font-weight:600;line-height:29px;width:var( --container-widget-width, 100% );max-width:100%;--container-widget-width:100%;--container-widget-flex-grow:0;}.elementor-widget-icon.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-primary );}.elementor-widget-icon.elementor-view-framed .elementor-icon, .elementor-widget-icon.elementor-view-default .elementor-icon{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-widget-icon.elementor-view-framed .elementor-icon, .elementor-widget-icon.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-primary );}.elementor-240 .elementor-element.elementor-element-690b545 .elementor-icon-wrapper{text-align:start;}.elementor-240 .elementor-element.elementor-element-690b545 .elementor-icon{font-size:25px;}.elementor-240 .elementor-element.elementor-element-690b545 .elementor-icon svg{height:25px;}@media(max-width:1750px){.elementor-240 .elementor-element.elementor-element-8e57bd4{font-size:17px;}}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"240\" class=\"elementor elementor-240 e-loop-item e-loop-item-2441 post-2441 post type-post status-publish format-standard has-post-thumbnail hentry category-non-classe\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-48639b8 e-flex e-con-boxed e-con e-parent\" data-id=\"48639b8\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/cytec-europe.com\/en\/cytec-poursuit-sa-progression-en-matiere-de-performance-rse-avec-ecovadis\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3582654 elementor-widget elementor-widget-image\" data-id=\"3582654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"711\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/04\/medaille-ecovadis-cytec-2026.jpg\" class=\"attachment-large size-large wp-image-2442\" alt=\"M\u00e9daille EcoVadis 2026 d\u00e9cern\u00e9e \u00e0 Cytec pour ses performances RSE\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/04\/medaille-ecovadis-cytec-2026.jpg 900w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/04\/medaille-ecovadis-cytec-2026-300x267.jpg 300w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/04\/medaille-ecovadis-cytec-2026-768x683.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-804f584 e-con-full e-flex e-con e-child\" data-id=\"804f584\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e57bd4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8e57bd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tCYTEC poursuit sa progression en mati\u00e8re de performance RSE avec EcoVadis\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-690b545 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"690b545\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"240\" class=\"elementor elementor-240 e-loop-item e-loop-item-223 post-223 post type-post status-publish format-standard has-post-thumbnail hentry category-non-classe\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-48639b8 e-flex e-con-boxed e-con e-parent\" data-id=\"48639b8\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/cytec-europe.com\/en\/notre-demarche-gpi-pour-un-environnement-durable\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3582654 elementor-widget elementor-widget-image\" data-id=\"3582654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/zone-gpi-cytec.jpg\" class=\"attachment-large size-large wp-image-220\" alt=\"\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/zone-gpi-cytec.jpg 945w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/zone-gpi-cytec-300x300.jpg 300w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/zone-gpi-cytec-150x150.jpg 150w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/zone-gpi-cytec-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-804f584 e-con-full e-flex e-con e-child\" data-id=\"804f584\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e57bd4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8e57bd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tNotre d\u00e9marche GPI pour un environnement durable\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-690b545 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"690b545\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"240\" class=\"elementor elementor-240 e-loop-item e-loop-item-252 post-252 post type-post status-publish format-standard has-post-thumbnail hentry category-non-classe\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-48639b8 e-flex e-con-boxed e-con e-parent\" data-id=\"48639b8\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/cytec-europe.com\/en\/cytec-accompagne-leni-metz-racing-team-pour-la-saison-2025-de-formula-student\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3582654 elementor-widget elementor-widget-image\" data-id=\"3582654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/CYTEC-ENI_METZ_RACING-FORMULA-STUDENT-vignette.jpg\" class=\"attachment-large size-large wp-image-219\" alt=\"\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/CYTEC-ENI_METZ_RACING-FORMULA-STUDENT-vignette.jpg 900w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/CYTEC-ENI_METZ_RACING-FORMULA-STUDENT-vignette-300x300.jpg 300w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/CYTEC-ENI_METZ_RACING-FORMULA-STUDENT-vignette-150x150.jpg 150w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/CYTEC-ENI_METZ_RACING-FORMULA-STUDENT-vignette-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-804f584 e-con-full e-flex e-con e-child\" data-id=\"804f584\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e57bd4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8e57bd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tCytec accompagne l\u2019ENI Metz Racing Team pour la saison 2025 de Formula Student\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-690b545 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"690b545\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"240\" class=\"elementor elementor-240 e-loop-item e-loop-item-1 post-1 post type-post status-publish format-standard has-post-thumbnail hentry category-non-classe\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-48639b8 e-flex e-con-boxed e-con e-parent\" data-id=\"48639b8\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/cytec-europe.com\/en\/bonjour-tout-le-monde\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3582654 elementor-widget elementor-widget-image\" data-id=\"3582654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/cytec-fin-annee.jpg\" class=\"attachment-large size-large wp-image-221\" alt=\"\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/cytec-fin-annee.jpg 900w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/cytec-fin-annee-300x300.jpg 300w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/cytec-fin-annee-150x150.jpg 150w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/cytec-fin-annee-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-804f584 e-con-full e-flex e-con e-child\" data-id=\"804f584\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e57bd4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8e57bd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tSoir\u00e9e de fin d\u2019ann\u00e9e CYTEC, un moment convivial pour cl\u00f4turer 2025\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-690b545 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"690b545\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"240\" class=\"elementor elementor-240 e-loop-item e-loop-item-2723 post-2723 post type-post status-publish format-standard has-post-thumbnail hentry category-non-classe\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-48639b8 e-flex e-con-boxed e-con e-parent\" data-id=\"48639b8\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/cytec-europe.com\/en\/lapproche-par-elements-finis-pour-des-produits-performants-et-durables\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3582654 elementor-widget elementor-widget-image\" data-id=\"3582654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"711\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/05\/approche-element-finis.jpg\" class=\"attachment-large size-large wp-image-2724\" alt=\"approche par \u00e9l\u00e9ments finis\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/05\/approche-element-finis.jpg 900w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/05\/approche-element-finis-300x267.jpg 300w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/05\/approche-element-finis-768x683.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-804f584 e-con-full e-flex e-con e-child\" data-id=\"804f584\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e57bd4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8e57bd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tL\u2019approche \u00ab par \u00e9l\u00e9ments finis \u00bb pour des produits performants et durables !\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-690b545 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"690b545\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"240\" class=\"elementor elementor-240 e-loop-item e-loop-item-2721 post-2721 post type-post status-publish format-standard has-post-thumbnail hentry category-non-classe\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-48639b8 e-flex e-con-boxed e-con e-parent\" data-id=\"48639b8\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/cytec-europe.com\/en\/pourquoi-choisir-le-rotomoulage-pour-vos-pieces-plastiques-techniques\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3582654 elementor-widget elementor-widget-image\" data-id=\"3582654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/cytec-plastique-4-1024x681.webp\" class=\"attachment-large size-large wp-image-1959\" alt=\"Machine de production plastique Cytec\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/cytec-plastique-4-1024x681.webp 1024w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/cytec-plastique-4-300x200.webp 300w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/cytec-plastique-4-768x511.webp 768w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/cytec-plastique-4.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-804f584 e-con-full e-flex e-con e-child\" data-id=\"804f584\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e57bd4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8e57bd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tPourquoi choisir le rotomoulage pour vos pi\u00e8ces plastiques techniques ?\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-690b545 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"690b545\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"240\" class=\"elementor elementor-240 e-loop-item e-loop-item-2718 post-2718 post type-post status-publish format-standard has-post-thumbnail hentry category-non-classe\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-48639b8 e-flex e-con-boxed e-con e-parent\" data-id=\"48639b8\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/cytec-europe.com\/en\/cytec-soutient-les-rangers-mosellans-pour-le-4l-trophy-2025\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3582654 elementor-widget elementor-widget-image\" data-id=\"3582654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/05\/4L-trophy-rangers-mosellans-cytec.jpg\" class=\"attachment-large size-large wp-image-2719\" alt=\"4L Trophy Rangers Mosellans\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/05\/4L-trophy-rangers-mosellans-cytec.jpg 900w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/05\/4L-trophy-rangers-mosellans-cytec-300x200.jpg 300w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/05\/4L-trophy-rangers-mosellans-cytec-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-804f584 e-con-full e-flex e-con e-child\" data-id=\"804f584\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e57bd4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8e57bd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tCYTEC SOUTIENT LES RANGERS MOSELLANS POUR LE 4L TROPHY 2025\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-690b545 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"690b545\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"240\" class=\"elementor elementor-240 e-loop-item e-loop-item-2715 post-2715 post type-post status-publish format-standard has-post-thumbnail hentry category-non-classe\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-48639b8 e-flex e-con-boxed e-con e-parent\" data-id=\"48639b8\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/cytec-europe.com\/en\/le-saviez-vous-cytec-sengage-pour-le-recyclage-des-plastiques\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3582654 elementor-widget elementor-widget-image\" data-id=\"3582654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/05\/recyclage-plastique-cytec.jpg\" class=\"attachment-large size-large wp-image-2716\" alt=\"Seau de plastique recycl\u00e9\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/05\/recyclage-plastique-cytec.jpg 900w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/05\/recyclage-plastique-cytec-300x200.jpg 300w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/05\/recyclage-plastique-cytec-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-804f584 e-con-full e-flex e-con e-child\" data-id=\"804f584\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e57bd4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8e57bd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLe saviez-vous ? CYTEC s\u2019engage pour le recyclage des plastiques !\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-690b545 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"690b545\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>News<\/p>","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-8","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Suivez les actualit\u00e9s de nos innovations, projets et nouveaut\u00e9s - CYTEC<\/title>\n<meta name=\"description\" content=\"Suivez les actualit\u00e9s CYTEC : innovations, projets industriels, nouveaut\u00e9s en thermoformage et rotomoulage plastique sur mesure.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cytec-europe.com\/en\/actualites\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suivez les actualit\u00e9s de nos innovations, projets et nouveaut\u00e9s - CYTEC\" \/>\n<meta property=\"og:description\" content=\"Suivez les actualit\u00e9s CYTEC : innovations, projets industriels, nouveaut\u00e9s en thermoformage et rotomoulage plastique sur mesure.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cytec-europe.com\/en\/actualites\/\" \/>\n<meta property=\"og:site_name\" content=\"CYTEC\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T11:31:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/actualites\\\/\",\"url\":\"https:\\\/\\\/cytec-europe.com\\\/actualites\\\/\",\"name\":\"Suivez les actualit\u00e9s de nos innovations, projets et nouveaut\u00e9s - CYTEC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/#website\"},\"datePublished\":\"2026-03-24T08:51:33+00:00\",\"dateModified\":\"2026-05-05T11:31:14+00:00\",\"description\":\"Suivez les actualit\u00e9s CYTEC : innovations, projets industriels, nouveaut\u00e9s en thermoformage et rotomoulage plastique sur mesure.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/actualites\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cytec-europe.com\\\/actualites\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/actualites\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cytec-europe.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/#website\",\"url\":\"https:\\\/\\\/cytec-europe.com\\\/\",\"name\":\"CYTEC\",\"description\":\"CYTEC, entreprise de plasturgie bas\u00e9e en Moselle, sp\u00e9cialis\u00e9e dans la transformation des mati\u00e8res plastiques par thermoformage et rotomoulage.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cytec-europe.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Suivez les actualit\u00e9s de nos innovations, projets et nouveaut\u00e9s - CYTEC","description":"Suivez les actualit\u00e9s CYTEC : innovations, projets industriels, nouveaut\u00e9s en thermoformage et rotomoulage plastique sur mesure.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cytec-europe.com\/en\/actualites\/","og_locale":"en_GB","og_type":"article","og_title":"Suivez les actualit\u00e9s de nos innovations, projets et nouveaut\u00e9s - CYTEC","og_description":"Suivez les actualit\u00e9s CYTEC : innovations, projets industriels, nouveaut\u00e9s en thermoformage et rotomoulage plastique sur mesure.","og_url":"https:\/\/cytec-europe.com\/en\/actualites\/","og_site_name":"CYTEC","article_modified_time":"2026-05-05T11:31:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cytec-europe.com\/actualites\/","url":"https:\/\/cytec-europe.com\/actualites\/","name":"Suivez les actualit\u00e9s de nos innovations, projets et nouveaut\u00e9s - CYTEC","isPartOf":{"@id":"https:\/\/cytec-europe.com\/#website"},"datePublished":"2026-03-24T08:51:33+00:00","dateModified":"2026-05-05T11:31:14+00:00","description":"Suivez les actualit\u00e9s CYTEC : innovations, projets industriels, nouveaut\u00e9s en thermoformage et rotomoulage plastique sur mesure.","breadcrumb":{"@id":"https:\/\/cytec-europe.com\/actualites\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cytec-europe.com\/actualites\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cytec-europe.com\/actualites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cytec-europe.com\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/cytec-europe.com\/#website","url":"https:\/\/cytec-europe.com\/","name":"CYTEC","description":"CYTEC, entreprise de plasturgie bas\u00e9e en Moselle, sp\u00e9cialis\u00e9e dans la transformation des mati\u00e8res plastiques par thermoformage et rotomoulage.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cytec-europe.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/pages\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":16,"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/pages\/8\/revisions"}],"predecessor-version":[{"id":2956,"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/pages\/8\/revisions\/2956"}],"wp:attachment":[{"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/media?parent=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}