{"id":6,"date":"2026-02-27T15:04:31","date_gmt":"2026-02-27T14:04:31","guid":{"rendered":""},"modified":"2026-07-15T12:24:55","modified_gmt":"2026-07-15T10:24:55","slug":"accueil","status":"publish","type":"page","link":"https:\/\/cytec-europe.com\/en\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6\" class=\"elementor elementor-6\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b85c24f e-con-full e-flex e-con e-parent\" data-id=\"b85c24f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3360bf4 elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3360bf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>NOUS DONNONS FORME \u00c0 VOS BESOINS<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8831a0 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"a8831a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Votre partenaire\nen thermoformage\net rotomoulage<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fe73ca elementor-widget elementor-widget-button\" data-id=\"2fe73ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/cytec-europe.com\/presentation\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrez notre savoir-faire<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-498109e e-con-full elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"498109e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<a class=\"elementor-element elementor-element-449d1fe e-con-full e-flex e-con e-child\" data-id=\"449d1fe\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/cytec-europe.com\/bureau-detude\/\">\n\t\t<div class=\"elementor-element elementor-element-3420ce1 e-con-full e-flex e-con e-child\" data-id=\"3420ce1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-239f2e1 elementor-widget elementor-widget-heading\" data-id=\"239f2e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bureau d'\u00e9tudes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ebaf91 elementor-widget elementor-widget-text-editor\" data-id=\"8ebaf91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9veloppement de solutions plastiques optimis\u00e9es, du prototypage \u00e0 l\u2019industrialisation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6c38e3 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f6c38e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd0804e elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-image\" data-id=\"dd0804e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"795\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/bureau-etude-developpement.webp\" class=\"attachment-large size-large wp-image-339\" alt=\"Bureau d\u2019\u00e9tude et d\u00e9veloppement\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/bureau-etude-developpement.webp 903w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/bureau-etude-developpement-300x298.webp 300w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/bureau-etude-developpement-150x150.webp 150w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/bureau-etude-developpement-768x763.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-af3dc39 e-con-full e-flex e-con e-child\" data-id=\"af3dc39\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/cytec-europe.com\/rotomoulage\/\">\n\t\t<div class=\"elementor-element elementor-element-8b96fa8 e-con-full e-flex e-con e-child\" data-id=\"8b96fa8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06c469f elementor-widget elementor-widget-heading\" data-id=\"06c469f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rotomoulage<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a6695d elementor-widget elementor-widget-text-editor\" data-id=\"3a6695d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Fabrication de pi\u00e8ces plastiques sur-mesure, r\u00e9sistantes et adapt\u00e9es aux environnements exigeants.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e91d7b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4e91d7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec98c25 elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-image\" data-id=\"ec98c25\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"556\" height=\"427\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/rotomoulage-vignette.webp\" class=\"attachment-large size-large wp-image-75\" alt=\"rotomoulage de pi\u00e8ces plastiques creuses par chauffage et rotation du moule\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/rotomoulage-vignette.webp 556w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/rotomoulage-vignette-300x230.webp 300w\" sizes=\"(max-width: 556px) 100vw, 556px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-21d3173 e-con-full e-flex e-con e-child\" data-id=\"21d3173\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/cytec-europe.com\/thermoformage\/\">\n\t\t<div class=\"elementor-element elementor-element-1121e20 e-con-full e-flex e-con e-child\" data-id=\"1121e20\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-784ff53 elementor-widget elementor-widget-heading\" data-id=\"784ff53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Thermoformage<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c390a6 elementor-widget elementor-widget-text-editor\" data-id=\"6c390a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Conception de pi\u00e8ces techniques sur mesure pour moyennes et grandes s\u00e9ries industrielles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f7c760 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"8f7c760\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13394ed elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-image\" data-id=\"13394ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"764\" height=\"448\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/thermoformage-vignette.webp\" class=\"attachment-large size-large wp-image-76\" alt=\"thermoformage de mati\u00e8res plastiques par chauffage et mise en forme\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/thermoformage-vignette.webp 764w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/thermoformage-vignette-300x176.webp 300w\" sizes=\"(max-width: 764px) 100vw, 764px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-81fb85e e-con-full elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet e-flex e-con e-parent\" data-id=\"81fb85e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<a class=\"elementor-element elementor-element-c1931fd e-con-full e-flex e-con e-child\" data-id=\"c1931fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/cytec-europe.com\/bureau-detude\/\">\n\t\t<div class=\"elementor-element elementor-element-4f334b1 e-con-full e-flex e-con e-child\" data-id=\"4f334b1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b5cc5f elementor-widget elementor-widget-heading\" data-id=\"7b5cc5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bureau d'\u00e9tudes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9eefe80 elementor-widget elementor-widget-text-editor\" data-id=\"9eefe80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9veloppement de solutions plastiques optimis\u00e9es, du prototypage \u00e0 l\u2019industrialisation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2721d28 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"2721d28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72e4fb9 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"72e4fb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"795\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/bureau-etude-developpement.webp\" class=\"attachment-large size-large wp-image-339\" alt=\"Bureau d\u2019\u00e9tude et d\u00e9veloppement\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/bureau-etude-developpement.webp 903w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/bureau-etude-developpement-300x298.webp 300w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/bureau-etude-developpement-150x150.webp 150w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/bureau-etude-developpement-768x763.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-0a22ed9 e-con-full e-flex e-con e-child\" data-id=\"0a22ed9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/cytec-europe.com\/rotomoulage\/\">\n\t\t<div class=\"elementor-element elementor-element-5b0b3ea e-con-full e-flex e-con e-child\" data-id=\"5b0b3ea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d5a27f elementor-widget elementor-widget-heading\" data-id=\"8d5a27f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rotomoulage<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba64bfb elementor-widget elementor-widget-text-editor\" data-id=\"ba64bfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Fabrication de pi\u00e8ces plastiques sur-mesure, r\u00e9sistantes et adapt\u00e9es aux environnements exigeants.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25a91a7 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"25a91a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ef8f5a elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"8ef8f5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"556\" height=\"427\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/rotomoulage-vignette.webp\" class=\"attachment-large size-large wp-image-75\" alt=\"rotomoulage de pi\u00e8ces plastiques creuses par chauffage et rotation du moule\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/rotomoulage-vignette.webp 556w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/rotomoulage-vignette-300x230.webp 300w\" sizes=\"(max-width: 556px) 100vw, 556px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-2af73d3 e-con-full e-flex e-con e-child\" data-id=\"2af73d3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/cytec-europe.com\/thermoformage\/\">\n\t\t<div class=\"elementor-element elementor-element-ef43581 e-con-full e-flex e-con e-child\" data-id=\"ef43581\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-685bc64 elementor-widget elementor-widget-heading\" data-id=\"685bc64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Thermoformage<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ffb14f elementor-widget elementor-widget-text-editor\" data-id=\"7ffb14f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Conception de pi\u00e8ces techniques sur mesure pour moyennes et grandes s\u00e9ries industrielles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f36783e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f36783e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f37ac02 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"f37ac02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"764\" height=\"448\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/thermoformage-vignette.webp\" class=\"attachment-large size-large wp-image-76\" alt=\"thermoformage de mati\u00e8res plastiques par chauffage et mise en forme\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/thermoformage-vignette.webp 764w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/thermoformage-vignette-300x176.webp 300w\" sizes=\"(max-width: 764px) 100vw, 764px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b3eac5 e-con-full e-flex e-con e-parent\" data-id=\"4b3eac5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b9d8704 e-con-full e-flex e-con e-child\" data-id=\"b9d8704\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad527f7 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ad527f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un partenaire industriel \nau service de vos projets<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c136c7 elementor-widget elementor-widget-image\" data-id=\"7c136c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"629\" height=\"614\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/SGS-iso-9001.webp\" class=\"attachment-large size-large wp-image-318\" alt=\"Certification SGS ISO 9001\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/SGS-iso-9001.webp 629w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/SGS-iso-9001-300x293.webp 300w\" sizes=\"(max-width: 629px) 100vw, 629px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d0acda elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"9d0acda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Depuis plus de 25 ans, <strong>CYTEC<\/strong> est sp\u00e9cialiste de la <strong>fabrication de pi\u00e8ces plastiques sur mesure.<\/strong> Nous accompagnons des secteurs vari\u00e9s tels que <strong>les \u00e9quipementiers industriels, l\u2019industrie automobile, le secteur militaire ou encore le domaine m\u00e9dical,<\/strong> en proposant des solutions adapt\u00e9es \u00e0 chaque besoin.<\/p><p>Gr\u00e2ce \u00e0 notre expertise en <strong>transformation de plastique,<\/strong> nous r\u00e9alisons des pi\u00e8ces techniques pr\u00e9cises tout en diversifiant notre offre. Aujourd\u2019hui, <strong>CYTEC<\/strong> propose \u00e9galement des <strong>produits plastiques utilitaires,<\/strong> con\u00e7us selon les m\u00eames standards de qualit\u00e9 : <strong>cache-feu pour travaux, signalisation routi\u00e8re,<\/strong> et autres solutions pratiques issues de notre savoir-faire en <strong>plasturgie sur mesure.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-676a7f9 e-con-full e-flex e-con e-parent\" data-id=\"676a7f9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d344cf custom-slide elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"6d344cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;6&quot;,&quot;slides_to_scroll&quot;:&quot;6&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:18,&quot;sizes&quot;:[]},&quot;autoplay_speed&quot;:1500,&quot;speed&quot;:400,&quot;slides_to_show_laptop&quot;:&quot;5&quot;,&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll_laptop&quot;:&quot;5&quot;,&quot;slides_to_scroll_tablet&quot;:&quot;3&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;image_spacing_custom_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/rotomoulage-thermoformage-viessmann.webp\" alt=\"Rotomoulage et thermoformage Viessmann\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/rotomoulage-thermoformage-novall-trotinette.webp\" alt=\"Rotomoulage et thermoformage Novall trottinette\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/rotomoulage-thermoformage-matev.webp\" alt=\"Rotomoulage et thermoformage Matev\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/rotomoulage-thermoformage-u2r.webp\" alt=\"Rotomoulage et thermoformage U2R\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/rotomoulage-thermoformage-japy-tech.webp\" alt=\"Rotomoulage et thermoformage Japy Tech\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/rotomoulage-thermoformage-aci.webp\" alt=\"Rotomoulage et thermoformage ACI\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/rotomoulage-thermoformage-emotors.webp\" alt=\"Rotomoulage et thermoformage Emotors\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 sur 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/rotomoulage-thermoformage-acreos.webp\" alt=\"Rotomoulage et thermoformage Acreos\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 sur 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/rotomoulage-thermoformage-aximum.webp\" alt=\"Rotomoulage et thermoformage Aximum\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 sur 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/rotomoulage-thermoformage-kavo.webp\" alt=\"Rotomoulage et thermoformage KaVo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 sur 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/07\/control-box.png\" alt=\"control box\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f9a7bb4 e-con-full e-flex e-con e-parent\" data-id=\"f9a7bb4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3a9718f e-con-full e-flex e-con e-child\" data-id=\"3a9718f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2141a52 e-con-full e-flex e-con e-child\" data-id=\"2141a52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eecdc22 elementor-widget elementor-widget-image\" data-id=\"eecdc22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/04\/bureau-etudes-cytec-ingenierie-prototypage-ecoconception.webp\" class=\"attachment-large size-large wp-image-2444\" alt=\"Bureau d\u2019\u00e9tudes Cytec ing\u00e9nierie prototypage \u00e9coconception\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/04\/bureau-etudes-cytec-ingenierie-prototypage-ecoconception.webp 902w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/04\/bureau-etudes-cytec-ingenierie-prototypage-ecoconception-300x200.webp 300w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/04\/bureau-etudes-cytec-ingenierie-prototypage-ecoconception-768x511.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5197f45 e-con-full e-flex e-con e-child\" data-id=\"5197f45\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2441c9a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"2441c9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Bureau d\u2019\u00e9tudes CYTEC<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be24847 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"be24847\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ing\u00e9nierie, prototypage et \u00e9coconception<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f06996f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"f06996f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Le bureau d\u2019\u00e9tudes CYTEC accompagne le d\u00e9veloppement de solutions plastiques sur mesure en thermoformage et rotomoulage. Gr\u00e2ce \u00e0 plus de 25 ans d\u2019expertise, \u00e0 des outils de conception CAO avanc\u00e9s, \u00e0 l\u2019impression 3D et \u00e0 la simulation num\u00e9rique, nos ing\u00e9nieurs et techniciens con\u00e7oivent des produits optimis\u00e9s, durables et performants.<br \/>D\u00e9couvrez l\u2019expertise et la m\u00e9thodologie de notre bureau d\u2019\u00e9tudes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25d2010 elementor-widget elementor-widget-button\" data-id=\"25d2010\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/cytec-europe.com\/bureau-detude\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrir le bureau d'\u00e9tudes<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92e4122 e-con-full e-flex e-con e-child\" data-id=\"92e4122\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3035242 e-con-full e-flex e-con e-child\" data-id=\"3035242\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8f3a6f elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d8f3a6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">la charte recyclage CYTEC<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a64e8e elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"8a64e8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00e9duction de l\u2019empreinte carbone\net \u00e9conomie circulaire<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6952d51 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6952d51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Chez CYTEC, la r\u00e9duction de l\u2019empreinte carbone guide chacune de nos actions. <br \/>De la r\u00e9cup\u00e9ration des produits en fin de vie \u00e0 l\u2019int\u00e9gration de mati\u00e8res recycl\u00e9es d\u00e8s la conception, en passant par une politique ambitieuse d\u2019\u00e9conomies d\u2019\u00e9nergie, nous inscrivons notre d\u00e9marche dans une logique durable, responsable et performante. <br \/>D\u00e9couvrez en d\u00e9tail nos engagements et nos actions concr\u00e8tes en faveur d\u2019une industrie plus vertueuse.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62f40a9 elementor-widget elementor-widget-button\" data-id=\"62f40a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/cytec-europe.com\/engagements\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus sur notre d\u00e9marche<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f722321 e-con-full e-flex e-con e-child\" data-id=\"f722321\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d6d074 elementor-widget elementor-widget-image\" data-id=\"3d6d074\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/reduction-empreinte-carbone-economie-circulaire-1024x576.webp\" class=\"attachment-large size-large wp-image-147\" alt=\"R\u00e9duction de l\u2019empreinte carbone et \u00e9conomie circulaire\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/reduction-empreinte-carbone-economie-circulaire-1024x576.webp 1024w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/reduction-empreinte-carbone-economie-circulaire-300x169.webp 300w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/reduction-empreinte-carbone-economie-circulaire-768x432.webp 768w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/reduction-empreinte-carbone-economie-circulaire.webp 1244w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e3c8921 e-con-full e-flex e-con e-parent\" data-id=\"e3c8921\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-67d4aef e-con-full e-flex e-con e-child\" data-id=\"67d4aef\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96a47ef e-con-full e-flex e-con e-child\" data-id=\"96a47ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a6ba90 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"5a6ba90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un partenaire industriel \nengag\u00e9 \u00e0 vos c\u00f4t\u00e9s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7874689 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7874689\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tCYTEC met son expertise et ses moyens industriels au service de vos projets. Notre organisation flexible et notre accompagnement personnalis\u00e9 nous permettent de r\u00e9pondre efficacement \u00e0 vos contraintes techniques, \u00e9conomiques et environnementales.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c38ed1 elementor-widget elementor-widget-button\" data-id=\"4c38ed1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/cytec-europe.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-00b7b83 e-con-full e-flex e-con e-parent\" data-id=\"00b7b83\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f898891 e-con-full e-flex e-con e-child\" data-id=\"f898891\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0cccc20 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"0cccc20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-501be4a6-2104-4241-a356-ac7426ec3225\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M194.96,103.81c-1.58,8.67-4.82,18.04-9.71,28.12l-74.56,146.97v27.41h125.49v-27.88h-88.21l71.94-141.3c5.25-11.02,8.84-21.1,10.76-30.24,1.92-9.13,2.89-19.53,2.89-31.19v-25.99c0-12.6-3.41-21.97-10.24-28.12-6.83-6.14-17.25-9.22-31.24-9.22h-40.43c-14.01,0-24.42,3.07-31.24,9.22-6.83,6.14-10.24,15.52-10.24,28.12v57.18h35.71v-51.98c0-6.3,1.05-10.31,3.15-12.05,2.1-1.73,6.47-2.6,13.13-2.6h18.9c7,0,11.46.87,13.39,2.6,1.92,1.74,2.89,5.75,2.89,12.05v18.9c0,11.34-.79,21.35-2.36,30.01Z\"><\/path><path d=\"M388.18,297.09c6.83-6.14,10.24-15.51,10.24-28.12v-106.33c0-12.6-3.41-21.97-10.24-28.12-6.83-6.14-17.25-9.21-31.24-9.21h-50.41V40.25h91.89V12.37h-128.12v140.83h75.61c7,0,11.46.87,13.39,2.6,1.92,1.74,2.89,5.75,2.89,12.05v95.93c0,5.99-.97,9.92-2.89,11.81-1.93,1.89-6.39,2.84-13.39,2.84h-23.1c-6.65,0-11.03-.94-13.13-2.84-2.1-1.89-3.15-5.83-3.15-11.81v-48.2h-36.23v53.4c0,12.6,3.41,21.97,10.24,28.12,6.83,6.14,17.24,9.22,31.24,9.22h45.16c14,0,24.42-3.07,31.24-9.22Z\"><\/path><path d=\"M173.1,359.18c-.94-2.49-2.36-4.45-4.27-5.86-3.76-2.77-8.6-4.15-14.51-4.15h-13.66c-9.11,0-15.88,2-20.32,5.99-4.44,4-6.66,10.09-6.66,18.29v100.5c0,8.2,2.22,14.29,6.66,18.29,4.44,4,11.21,5.99,20.32,5.99h13.66c5.92,0,10.76-1.38,14.51-4.15,1.91-1.41,3.33-3.36,4.27-5.86v10.01h23.56v-149.06h-23.56v10.01ZM173.1,386.97v82.06c0,4.1-.91,6.97-2.73,8.61-1.83,1.64-4.78,2.46-8.88,2.46h-13.66c-4.33,0-7.17-.61-8.54-1.84-1.37-1.23-2.05-3.79-2.05-7.68v-93.74c0-4.1.68-6.71,2.05-7.84,1.37-1.12,4.21-1.69,8.54-1.69h13.66c4.1,0,7.05.82,8.88,2.46,1.82,1.64,2.73,4.51,2.73,8.61v8.61Z\"><\/path><path d=\"M283.4,349.17h-13.66c-5.92,0-10.76,1.38-14.51,4.15-1.91,1.41-3.33,3.36-4.27,5.86v-10.01h-23.56v149.06h23.56v-119.87c0-4.1.91-6.96,2.73-8.61,1.82-1.64,4.78-2.46,8.88-2.46h13.66c4.55,0,7.45.57,8.71,1.69,1.25,1.13,1.88,3.74,1.88,7.84v121.4h23.56v-124.78c0-8.19-2.22-14.29-6.66-18.29-4.44-4-11.22-5.99-20.32-5.99Z\"><\/path><path d=\"M408.55,421.24c-4.44-4-11.22-5.99-20.32-5.99h-16.73c-4.33,0-7.17-.61-8.54-1.84s-2.05-3.79-2.05-7.68v-29.2c0-4.1.68-6.71,2.05-7.84,1.37-1.12,4.21-1.69,8.54-1.69h9.56c4.55,0,7.45.57,8.71,1.69,1.25,1.13,1.88,3.74,1.88,7.84v11.99h23.22v-15.06c0-8.19-2.22-14.29-6.66-18.29-4.44-4-11.22-5.99-20.32-5.99h-23.22c-9.11,0-15.88,2-20.32,5.99-4.44,4-6.66,10.09-6.66,18.29v35.34c0,8.2,2.22,14.29,6.66,18.29,4.44,4,11.21,5.99,20.32,5.99h16.73c4.55,0,7.45.57,8.71,1.69,1.25,1.13,1.88,3.74,1.88,7.84v28.28c0,3.89-.63,6.45-1.88,7.68-1.25,1.23-4.16,1.84-8.71,1.84h-9.22c-4.33,0-7.17-.61-8.54-1.84-1.37-1.23-2.05-3.79-2.05-7.68v-11.99h-23.22v15.06c0,8.2,2.22,14.29,6.66,18.29,4.44,4,11.21,5.99,20.32,5.99h22.88c9.1,0,15.88-2,20.32-5.99,4.44-4,6.66-10.09,6.66-18.29v-34.42c0-8.19-2.22-14.29-6.66-18.29Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ae270ad e-con-full e-flex e-con e-child\" data-id=\"ae270ad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e0e9f4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6e0e9f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Expertise technique<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0da832d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0da832d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Plus de 25 ans d\u2019exp\u00e9rience en rotomoulage et thermoformage<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-82cdde7 e-con-full e-flex e-con e-child\" data-id=\"82cdde7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b78fc94 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b78fc94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-f9b6c604-fec3-47e0-ac2a-4206b6ac7758\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M488.27,61.36l-37-36.89c-13.75-13.71-36.38-14.92-50.6-.78L35.04,387.14c-2.27,2.26-3.82,4.33-4.25,7.47l-12.19,88.73c-.78,5.66,4.5,12.23,9.98,11.47l88.6-12.25c2.52-.35,4.02-1.46,5.54-2.98L489.59,112.59c14.5-14.5,12.62-37.34-1.32-51.24ZM38.93,471.37l8.17-52.9,44.53,44.37-52.7,8.53ZM114.68,455.89l-59.43-59.23L380.48,71.43l59.33,59.31L114.68,455.89ZM473.08,97.23c-6.44,6.83-12.41,13.1-19.21,18.87l-58.9-59.02,18.22-18.31c6.28-6.31,16.4-6.22,22.74.12l36.43,36.44c5.77,5.77,6.74,15.52.72,21.9Z\"><\/path><path d=\"M148.26,249.37l14.31-14.32-38.68-38.89,26.33-26.48-14.21-14.3-26.57,26.37-26.52-26.45,45.18-45.2-14.77-15.04-44.68,45.71-23.27-22.95c-2.25-2.22-2.48-5.52-.03-7.79L113.81,42.51c2.18-2.15,5.25-3.39,7.85-.79l117.63,117.56,14.37-14.34L135.39,25.93c-9.44-9.5-26.18-8.35-35.42.9L29.73,97.14c-8.44,8.45-9.56,23.84-.9,32.52l119.43,119.71Z\"><\/path><path d=\"M367.38,257.63l-14.44,14.27,117.14,117.19c2.43,2.43,2.48,5.5.1,7.85l-68.99,67.99c-2.33,2.37-5.49,2.1-7.73-.05l-22.97-22.04,26.24-26.65-14.2-14.28-26.67,26.4-26.26-26.74,44.65-44.74-14.22-15.35-45.12,44.77-38.71-38.62-14.24,14.41,119.1,118.9c8.79,8.77,24.04,9.4,33,.46l71.76-71.63c8.44-8.42,9.48-23.88.88-32.5l-119.32-119.65Z\"><\/path><path d=\"M103.86,421.78L404.97,120.65c-4.62-5.02-9.41-10.06-14.53-14.39L89.27,407.42c4.41,5.01,9.32,10.39,14.59,14.36Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c5021f e-con-full e-flex e-con e-child\" data-id=\"6c5021f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d36bd52 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d36bd52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tSolutions sur mesure\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7319c1d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7319c1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Conception et fabrication adapt\u00e9es \u00e0 vos besoins<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a084df1 e-con-full e-flex e-con e-child\" data-id=\"a084df1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3efb2b1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"3efb2b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-4923bfb9-9072-4d4e-ae76-822d258a13dd\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M454.74,366.37l1.41-.87c10.11-6.21,23.97-14.73,27.32-27.65,4.3-16.59,1.13-31.3-8.91-41.42l-41.58-41.91,74.43-73.37L372.69,47.3l-21.77,21.37-72.58.16-16.87,16.78-73.13.05-33.4-32.95L7.92,199.73l85.59,85.7-2.02,2.11c-1.94,2.03-3.87,3.21-5.58,4.26-.96.59-1.87,1.15-2.7,1.81-2.51,2.49-4.92,4.8-7.25,7.04-17.76,17.06-28.48,27.35-21.33,55.14,3.09,11.99,15.69,19.96,25.82,26.36l2.28,1.45.12,2.52c.62,13.29,1.32,28.35,12.01,37.91,8.56,7.65,22.34,15.82,39.41,11.28l2.78-.74.84,2.75c3.39,11.08,10.81,20.05,20.89,25.26,10.21,5.28,22.06,6.13,33.35,2.39l2.72-.9,1.01,2.68c6.05,16.01,20.17,26.49,36.85,27.36,17.27.88,32.74-8.29,40.35-23.97l1.58-3.26,2.9,2.18c12.14,9.14,25.51,11.39,39.73,6.68,12.04-3.99,21.67-13.54,25.77-25.55l.92-2.69,2.73.78c23.29,6.7,46.08-5.36,52.99-28.05l.83-2.71,2.75.68c17.18,4.26,30.74-3.62,39.09-10.98,10.66-9.39,12.24-24.38,12.36-39.18v-1.65ZM288.07,92.67l72.93-.21,12.09-11.18,99.85,99.84-56.76,56.78-102.89-102.93-30.76,30.46c-19.69,17.52-46.31,20.5-69.45,7.78l-3.48-1.91,78.47-78.63ZM94.14,359.54c-.09,0-.18,0-.27,0-4.79-.08-9.49-2.2-12.91-5.82h0c-6.76-7.16-6.6-17.81.39-24.76l15.84-15.76c3.21-3.19,7.5-4.94,12.12-4.86,4.82.06,9.46,2.06,12.74,5.48,6.79,7.09,6.68,18.04-.27,24.91l-16.22,16.07c-3.1,3.07-7.14,4.75-11.42,4.75ZM137.91,406.86c-3.75,3.78-8.6,5.69-13.39,5.69-4.41,0-8.78-1.62-12.21-4.88-3.38-3.22-5.35-7.84-5.4-12.68-.06-4.79,1.73-9.24,5.03-12.54l26.85-26.83c6.84-6.83,17.95-6.96,24.76-.28,3.53,3.46,5.57,8.22,5.6,13.06.03,4.48-1.67,8.68-4.8,11.83l-26.44,26.63ZM206.4,422.28h0l-15.61,15.73c-3.59,3.62-8.25,5.44-12.89,5.44-4.38,0-8.75-1.62-12.19-4.88-3.46-3.28-5.48-7.92-5.54-12.72-.06-4.79,1.79-9.3,5.2-12.7l15.98-15.9c6.49-6.46,17.37-6.4,24.25.13,3.49,3.31,5.54,7.99,5.62,12.84.07,4.59-1.64,8.88-4.81,12.08ZM238.97,469.96c-1.37.29-2.72.42-4.04.42-7.68,0-14.27-4.68-16.77-12.32-2.01-6.16-.42-12.85,4.26-17.91,4.29-4.64,10.6-6.6,16.87-5.23,8.23,1.8,14.06,9.32,13.88,17.89-.18,8.25-6.15,15.46-14.19,17.14ZM430.62,336.44l-34.02-33.97-16.98,16.62,46.47,46.59c3.11,3.12,4.8,7.33,4.76,11.86-.04,4.79-2.06,9.58-5.41,12.81-7.05,6.81-17.97,6.77-24.85-.1l-45.89-45.83-16.9,16.81,33.57,33.48c7.6,7.58,8.16,18.47,1.33,25.89-3.24,3.52-7.58,5.51-12.21,5.6-5.12.12-10.43-2.15-14.46-6.2l-33.45-33.54-17.16,16.83,20.46,20.18c3.64,3.59,5.64,8.29,5.62,13.24-.02,4.71-1.92,9.13-5.34,12.45-3.49,3.38-8.03,5.07-12.54,5.07s-9.02-1.69-12.41-5.08l-27.21-27.17c-7.37-6.77-15.93-10.45-26.18-11.25l-2.54-.2-.2-2.54c-1.7-21.44-17.89-37.67-39.38-39.47l-2.52-.21-.2-2.52c-1.72-21.45-17.86-37.58-39.25-39.23l-2.49-.19-.25-2.49c-1.21-12.08-6.06-21.81-14.82-29.74l-.11-.1-94.41-94.24,113.34-113.31,23.25,22.9,59,.31-62.21,62.42c15.42,18.87,38.13,30.6,62.74,32.3,23.2,1.6,45.29-6.14,60.63-21.24l14.87-14.63,143.49,143.59c3.18,3.18,4.93,7.44,4.92,12-.01,4.78-1.99,9.59-5.29,12.87-7.09,7.03-18.39,6.78-25.75-.56Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0e64382 e-con-full e-flex e-con e-child\" data-id=\"0e64382\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-447f4d1 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"447f4d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t\nAccompagnement global\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1c9df8 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d1c9df8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDe l\u2019\u00e9tude \u00e0 la production en s\u00e9rie \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4753be e-con-full e-flex e-con e-parent\" data-id=\"a4753be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75af56e elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"75af56e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos actualit\u00e9s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b39df6c elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"b39df6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:240,&quot;_skin&quot;:&quot;post&quot;,&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-240\">.elementor-240 .elementor-element.elementor-element-48639b8{--display:flex;--gap:0px 0px;--row-gap:0px;--column-gap:0px;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-widget-image .widget-image-caption{color:var( --e-global-color-text );font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-weight:var( --e-global-typography-text-font-weight );}.elementor-240 .elementor-element.elementor-element-3582654 img{width:100%;height:400px;object-fit:cover;object-position:center center;}.elementor-240 .elementor-element.elementor-element-804f584{--display:flex;--padding-top:3%;--padding-bottom:3%;--padding-left:6%;--padding-right:6%;}.elementor-240 .elementor-element.elementor-element-804f584:not(.elementor-motion-effects-element-type-background), .elementor-240 .elementor-element.elementor-element-804f584 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:var( --e-global-color-secondary );}.elementor-widget-text-editor{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-weight:var( --e-global-typography-text-font-weight );color:var( --e-global-color-text );}.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:var( --e-global-color-primary );}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap, .elementor-widget-text-editor.elementor-drop-cap-view-default .elementor-drop-cap{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-240 .elementor-element.elementor-element-8e57bd4{font-family:\"bc-novatica-cyr\", Sans-serif;font-size:20px;font-weight:600;line-height:29px;width:var( --container-widget-width, 100% );max-width:100%;--container-widget-width:100%;--container-widget-flex-grow:0;}.elementor-widget-icon.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-primary );}.elementor-widget-icon.elementor-view-framed .elementor-icon, .elementor-widget-icon.elementor-view-default .elementor-icon{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-widget-icon.elementor-view-framed .elementor-icon, .elementor-widget-icon.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-primary );}.elementor-240 .elementor-element.elementor-element-690b545 .elementor-icon-wrapper{text-align:start;}.elementor-240 .elementor-element.elementor-element-690b545 .elementor-icon{font-size:25px;}.elementor-240 .elementor-element.elementor-element-690b545 .elementor-icon svg{height:25px;}@media(max-width:1750px){.elementor-240 .elementor-element.elementor-element-8e57bd4{font-size:17px;}}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"240\" class=\"elementor elementor-240 e-loop-item e-loop-item-2441 post-2441 post type-post status-publish format-standard has-post-thumbnail hentry category-non-classe\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-48639b8 e-flex e-con-boxed e-con e-parent\" data-id=\"48639b8\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/cytec-europe.com\/en\/cytec-poursuit-sa-progression-en-matiere-de-performance-rse-avec-ecovadis\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3582654 elementor-widget elementor-widget-image\" data-id=\"3582654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"711\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/04\/medaille-ecovadis-cytec-2026.jpg\" class=\"attachment-large size-large wp-image-2442\" alt=\"M\u00e9daille EcoVadis 2026 d\u00e9cern\u00e9e \u00e0 Cytec pour ses performances RSE\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/04\/medaille-ecovadis-cytec-2026.jpg 900w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/04\/medaille-ecovadis-cytec-2026-300x267.jpg 300w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/04\/medaille-ecovadis-cytec-2026-768x683.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-804f584 e-con-full e-flex e-con e-child\" data-id=\"804f584\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e57bd4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8e57bd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tCYTEC poursuit sa progression en mati\u00e8re de performance RSE avec EcoVadis\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-690b545 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"690b545\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"240\" class=\"elementor elementor-240 e-loop-item e-loop-item-223 post-223 post type-post status-publish format-standard has-post-thumbnail hentry category-non-classe\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-48639b8 e-flex e-con-boxed e-con e-parent\" data-id=\"48639b8\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/cytec-europe.com\/en\/notre-demarche-gpi-pour-un-environnement-durable\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3582654 elementor-widget elementor-widget-image\" data-id=\"3582654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/zone-gpi-cytec.jpg\" class=\"attachment-large size-large wp-image-220\" alt=\"\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/zone-gpi-cytec.jpg 945w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/zone-gpi-cytec-300x300.jpg 300w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/zone-gpi-cytec-150x150.jpg 150w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/zone-gpi-cytec-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-804f584 e-con-full e-flex e-con e-child\" data-id=\"804f584\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e57bd4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8e57bd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tNotre d\u00e9marche GPI pour un environnement durable\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-690b545 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"690b545\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"240\" class=\"elementor elementor-240 e-loop-item e-loop-item-252 post-252 post type-post status-publish format-standard has-post-thumbnail hentry category-non-classe\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-48639b8 e-flex e-con-boxed e-con e-parent\" data-id=\"48639b8\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/cytec-europe.com\/en\/cytec-accompagne-leni-metz-racing-team-pour-la-saison-2025-de-formula-student\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3582654 elementor-widget elementor-widget-image\" data-id=\"3582654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/CYTEC-ENI_METZ_RACING-FORMULA-STUDENT-vignette.jpg\" class=\"attachment-large size-large wp-image-219\" alt=\"\" srcset=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/CYTEC-ENI_METZ_RACING-FORMULA-STUDENT-vignette.jpg 900w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/CYTEC-ENI_METZ_RACING-FORMULA-STUDENT-vignette-300x300.jpg 300w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/CYTEC-ENI_METZ_RACING-FORMULA-STUDENT-vignette-150x150.jpg 150w, https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/02\/CYTEC-ENI_METZ_RACING-FORMULA-STUDENT-vignette-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-804f584 e-con-full e-flex e-con e-child\" data-id=\"804f584\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e57bd4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8e57bd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tCytec accompagne l\u2019ENI Metz Racing Team pour la saison 2025 de Formula Student\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-690b545 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"690b545\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a8fad1 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0a8fad1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/cytec-europe.com\/actualites\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5ed00a74-0ae4-4631-8d10-945e0ad427db\" data-name=\"Calque 1\" viewBox=\"0 0 512 512\"><path d=\"M177.67,499.62l-30.74-30.74c-3.26-3.26-3.26-8.53,0-11.79l200.9-200.9L146.93,55.28c-3.26-3.26-3.26-8.53,0-11.79l30.74-30.74c3.26-3.26,8.53-3.26,11.79,0l243.43,243.43-243.43,243.43c-3.26,3.26-8.53,3.26-11.79,0Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir toutes les actus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>NOUS DONNONS FORME \u00c0 VOS BESOINS Votre partenaire en thermoformage et rotomoulage D\u00e9couvrez notre savoir-faire Bureau d&rsquo;\u00e9tudes D\u00e9veloppement de solutions plastiques optimis\u00e9es, du prototypage \u00e0 l\u2019industrialisation. Rotomoulage Fabrication de pi\u00e8ces plastiques sur-mesure, r\u00e9sistantes et adapt\u00e9es aux environnements exigeants. Thermoformage Conception de pi\u00e8ces techniques sur mesure pour moyennes et grandes s\u00e9ries industrielles. Bureau d&rsquo;\u00e9tudes D\u00e9veloppement de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-6","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Thermoformage et Rotomoulage de pi\u00e8ces plastiques sur mesure - CYTEC<\/title>\n<meta name=\"description\" content=\"CYTEC con\u00e7oit et fabrique des pi\u00e8ces plastiques techniques par thermoformage et rotomoulage pour l\u2019industrie en France et en Europe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cytec-europe.com\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thermoformage et Rotomoulage de pi\u00e8ces plastiques sur mesure - CYTEC\" \/>\n<meta property=\"og:description\" content=\"CYTEC con\u00e7oit et fabrique des pi\u00e8ces plastiques techniques par thermoformage et rotomoulage pour l\u2019industrie en France et en Europe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cytec-europe.com\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"CYTEC\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T10:24:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/bureau-etude-developpement.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"903\" \/>\n\t<meta property=\"og:image:height\" content=\"897\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/\",\"url\":\"https:\\\/\\\/cytec-europe.com\\\/\",\"name\":\"Thermoformage et Rotomoulage de pi\u00e8ces plastiques sur mesure - CYTEC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cytec-europe.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/bureau-etude-developpement.webp\",\"datePublished\":\"2026-02-27T14:04:31+00:00\",\"dateModified\":\"2026-07-15T10:24:55+00:00\",\"description\":\"CYTEC con\u00e7oit et fabrique des pi\u00e8ces plastiques techniques par thermoformage et rotomoulage pour l\u2019industrie en France et en Europe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cytec-europe.com\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cytec-europe.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/bureau-etude-developpement.webp\",\"contentUrl\":\"https:\\\/\\\/cytec-europe.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/bureau-etude-developpement.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cytec-europe.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cytec-europe.com\\\/#website\",\"url\":\"https:\\\/\\\/cytec-europe.com\\\/\",\"name\":\"CYTEC\",\"description\":\"CYTEC, entreprise de plasturgie bas\u00e9e en Moselle, sp\u00e9cialis\u00e9e dans la transformation des mati\u00e8res plastiques par thermoformage et rotomoulage.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cytec-europe.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Thermoformage et Rotomoulage de pi\u00e8ces plastiques sur mesure - CYTEC","description":"CYTEC con\u00e7oit et fabrique des pi\u00e8ces plastiques techniques par thermoformage et rotomoulage pour l\u2019industrie en France et en Europe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cytec-europe.com\/en\/","og_locale":"en_GB","og_type":"article","og_title":"Thermoformage et Rotomoulage de pi\u00e8ces plastiques sur mesure - CYTEC","og_description":"CYTEC con\u00e7oit et fabrique des pi\u00e8ces plastiques techniques par thermoformage et rotomoulage pour l\u2019industrie en France et en Europe.","og_url":"https:\/\/cytec-europe.com\/en\/","og_site_name":"CYTEC","article_modified_time":"2026-07-15T10:24:55+00:00","og_image":[{"width":903,"height":897,"url":"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/bureau-etude-developpement.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cytec-europe.com\/","url":"https:\/\/cytec-europe.com\/","name":"Thermoformage et Rotomoulage de pi\u00e8ces plastiques sur mesure - CYTEC","isPartOf":{"@id":"https:\/\/cytec-europe.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cytec-europe.com\/#primaryimage"},"image":{"@id":"https:\/\/cytec-europe.com\/#primaryimage"},"thumbnailUrl":"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/bureau-etude-developpement.webp","datePublished":"2026-02-27T14:04:31+00:00","dateModified":"2026-07-15T10:24:55+00:00","description":"CYTEC con\u00e7oit et fabrique des pi\u00e8ces plastiques techniques par thermoformage et rotomoulage pour l\u2019industrie en France et en Europe.","breadcrumb":{"@id":"https:\/\/cytec-europe.com\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cytec-europe.com\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cytec-europe.com\/#primaryimage","url":"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/bureau-etude-developpement.webp","contentUrl":"https:\/\/cytec-europe.com\/wp-content\/uploads\/2026\/03\/bureau-etude-developpement.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/cytec-europe.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cytec-europe.com\/"},{"@type":"ListItem","position":2,"name":"Accueil"}]},{"@type":"WebSite","@id":"https:\/\/cytec-europe.com\/#website","url":"https:\/\/cytec-europe.com\/","name":"CYTEC","description":"CYTEC, entreprise de plasturgie bas\u00e9e en Moselle, sp\u00e9cialis\u00e9e dans la transformation des mati\u00e8res plastiques par thermoformage et rotomoulage.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cytec-europe.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/pages\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/comments?post=6"}],"version-history":[{"count":3,"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/pages\/6\/revisions"}],"predecessor-version":[{"id":2975,"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/pages\/6\/revisions\/2975"}],"wp:attachment":[{"href":"https:\/\/cytec-europe.com\/en\/wp-json\/wp\/v2\/media?parent=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}